{"id":2404,"date":"2019-03-04T15:29:25","date_gmt":"2019-03-04T12:29:25","guid":{"rendered":"\/blog\/?p=2404"},"modified":"2020-06-17T15:44:50","modified_gmt":"2020-06-17T12:44:50","slug":"aplicacao-find-my-kids-para-o-rastreamento-das-criancas","status":"publish","type":"post","link":"https:\/\/findmykids.org\/blog\/pt\/aplicacao-find-my-kids-para-o-rastreamento-das-criancas","title":{"rendered":"Aplica\u00e7\u00e3o Findmykids para o rastreamento das crian\u00e7as"},"content":{"rendered":"\r\n<p>H\u00e1 muitas raz\u00f5es pelas quais os pais podem precisar saber onde est\u00e3o os seus filhos &#8211; da simples curiosidade at\u00e9 \u00e0s preocupa\u00e7\u00f5es mais s\u00e9rias como a seguran\u00e7a dele ou dela. A aplica\u00e7\u00e3o <strong><a href=\"https:\/\/redirect.appmetrica.yandex.com\/serve\/98086341643935463?from=aplicacao-find-my-kids-para-o-rastreamento-das-criancas\">Findmykids<\/a><\/strong> para rastrear as crian\u00e7as tem exatamente essa fun\u00e7\u00e3o que identifica a localiza\u00e7\u00e3o do telefone de uma crian\u00e7a num mapa, em tempo real.<\/p>\r\n\r\n\r\n\r\n<h2><strong>Como funciona a aplica\u00e7\u00e3o Findmykids?<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>O <strong>Findmykids<\/strong> \u00e9 uma aplica\u00e7\u00e3o de acompanhamento infantil para Android \/ iOS que identifica a localiza\u00e7\u00e3o de uma crian\u00e7a ao triangular a posi\u00e7\u00e3o do telefone (a cada 15 minutos) num espa\u00e7o de alguns metros. Isso \u00e9 feito usando um sensor GPS embutido num telefone inteligente e sistemas de comunica\u00e7\u00e3o de Internet &#8211; Wi-Fi e Internet M\u00f3vel. Mas esta n\u00e3o \u00e9 a \u00fanica fun\u00e7\u00e3o da aplica\u00e7\u00e3o, tamb\u00e9m tem as fun\u00e7\u00f5es de:<\/p>\r\n\r\n\r\n\r\n<ul class=\"info\"><li>se necess\u00e1rio, grava sons em redor do telefone de uma crian\u00e7a;<\/li><li>define as configura\u00e7\u00f5es de um dispositivo que impedem o funcionamento normal da aplica\u00e7\u00e3o e ajuda a corrigi-las;<\/li><li>cria o hist\u00f3rico de localiza\u00e7\u00e3o do filho;<\/li><li>envia notifica\u00e7\u00f5es para o telefone de um pai se uma crian\u00e7a sair de uma \u00e1rea designada;<\/li><li>monitora a bateria do telem\u00f3vel da crian\u00e7a.<\/li><\/ul>\r\n\r\n\r\n\r\n<h2><strong>Benef\u00edcios da\r\naplica\u00e7\u00e3o Findmykids<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>As principais vantagens da aplica\u00e7\u00e3o <strong>Findmykids<\/strong> em rela\u00e7\u00e3o aos seus concorrentes s\u00e3o os seguintes recursos:<\/p>\r\n\r\n\r\n\r\n<ul class=\"info\"><li>interface intuitiva, que ser\u00e1 compreens\u00edvel para quase todos que j\u00e1 usaram um smartphone ou PC;<\/li><li>identifica\u00e7\u00e3o precisa e r\u00e1pida da localiza\u00e7\u00e3o da crian\u00e7a (o desvio m\u00e1ximo \u00e9 de at\u00e9 12m, a velocidade de localiza\u00e7\u00e3o \u00e9 de cerca de 5 segundos);<\/li><li>impacto m\u00ednimo na autonomia do dispositivo;<\/li><li>somente os pais t\u00eam direitos de administrador;<\/li><li>capacidade de adicionar um n\u00famero ilimitado de dispositivos para acompanhar crian\u00e7as ou entes queridos.<\/li><\/ul>\r\n\r\n\r\n\r\n<p>Tamb\u00e9m deve ser real\u00e7ado que a instala\u00e7\u00e3o da aplica\u00e7\u00e3o de rastreamento do seu filho <strong>Findmykids<\/strong> n\u00e3o exige acesso root. Isso aumenta a seguran\u00e7a do seu smartphone, pois um smartphone com acesso root \u00e9 muito mais suscet\u00edvel a v\u00edrus e interven\u00e7\u00e3o de terceiros que os outros.<\/p>\r\n\r\n\r\n\r\n<h2><strong>F\u00e1cil de\r\ninstalar, f\u00e1cil de usar<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>Para come\u00e7ar a usar a aplica\u00e7\u00e3o de rastreamento\r\ninfantil, vai precisar de executar cinco etapas simples:<\/p>\r\n\r\n\r\n\r\n<ol><li>Instale o <strong>Findmykids<\/strong> no smartphone dos pais (obtenha-o no <a href=\"https:\/\/redirect.appmetrica.yandex.com\/serve\/98086341643935463?from=aplicacao-find-my-kids-para-o-rastreamento-das-criancas\">Google Play<\/a> ou na <a href=\"https:\/\/redirect.appmetrica.yandex.com\/serve\/98086341643935463?from=aplicacao-find-my-kids-para-o-rastreamento-das-criancas\">AppStore<\/a>). Ele ir\u00e1 monitorar telefones dos seus filhos ou parentes.<\/li><li>Registe o seu filho\/Crie a conta do seu filho especificando o nome dele e adicionando uma foto. Esta informa\u00e7\u00e3o ser\u00e1 vis\u00edvel apenas para voc\u00ea.<\/li><li>Em seguida, coloque um c\u00f3digo especial para identificar o telefone do seu filho.<\/li><li>Instale o <strong>Findmykids<\/strong> no telefone do seu filho ou de um ente querido (esse telefone ser\u00e1 usado para identificar a localiza\u00e7\u00e3o da crian\u00e7a).<\/li><li>Digite o c\u00f3digo obtido na etapa 3 no telefone da crian\u00e7a.<\/li><\/ol>\r\n\r\n\r\n\r\n<p>No final, a aplica\u00e7\u00e3o mostrar\u00e1 como alterar as configura\u00e7\u00f5es do telefone para rastrear com precis\u00e3o a localiza\u00e7\u00e3o do seu filho. A instala\u00e7\u00e3o est\u00e1 conclu\u00edda e o aplicativo <strong>Findmykids<\/strong> est\u00e1 pronto para ser usado. Pode verificar a localiza\u00e7\u00e3o da crian\u00e7a ao visualizar o hist\u00f3rico de localiza\u00e7\u00e3o e fazer uma solicita\u00e7\u00e3o para localizar a posi\u00e7\u00e3o aqui e agora. Voc\u00ea tamb\u00e9m pode configurar uma determinada \u00e1rea onde ache que a crian\u00e7a estar\u00e1 segura. E se a crian\u00e7a ultrapassar os seus limites, uma mensagem ser\u00e1 enviada ao telefone dos pais, informando que a crian\u00e7a deixou uma zona segura. <\/p>\r\n\r\n\r\n\r\n<h2><strong>Tome uma\r\natitude!<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"warning\">Quer parar de se preocupar de uma vez por todas com o seu filho porque n\u00e3o sabe onde ele est\u00e1? Em seguida, n\u00e3o hesite e instale <strong>a aplica\u00e7\u00e3o de acompanhamento infantil para iOS \/ Android agora<\/strong>. Tendo feito isso,ser\u00e1 capaz de cuidar do seu filho sem incomod\u00e1-lo com os seus cuidados condescendentes, e se o pior acontecer \u2013 vai poder ajud\u00e1-lo imediatamente!<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1080\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as.jpg\" alt=\"\" class=\"wp-image-2363\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as.jpg 1920w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-808x455.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-392x221.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-1232x693.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-768x432.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-1024x576.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/02\/rel\u00f3gio-gps-para-crian\u00e7as-300x169.jpg 300w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption><br><\/figcaption><\/figure>\r\n\r\n\r\n\r\n<p style=\"text-align:center\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"52\" class=\"alignnone size-full wp-image-1578 aligncenter\" src=\"https:\/\/cdn-blog.findmykids.org\/2018\/09\/AppStore_GooglePlay_small.png\" alt=\"\"><a href=\"https:\/\/redirect.appmetrica.yandex.com\/serve\/98086341643935463?from=aplicacao-find-my-kids-para-o-rastreamento-das-criancas\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\"><\/a><\/p>\r\n\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"2404\"\n\t\t\t\t\tdata-ulike-nonce=\"e784ad63a6\"\n\t\t\t\t\tdata-ulike-type=\"likeThis\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-disable-pophover=\"0\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_likethis_2404\"><\/button><\/div><\/div>\n\t","protected":false},"excerpt":{"rendered":"<p>H\u00e1 muitas raz\u00f5es pelas quais os pais podem precisar saber onde est\u00e3o os seus filhos&#8230;<\/p>\n","protected":false},"author":4,"featured_media":16,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_edit_lock":["1592397760:4"],"classic-editor-remember":["classic-editor"],"_edit_last":["4"],"_wp_old_date":["2019-03-01"],"_thumbnail_id":["16"],"lang-ru":["15"],"lang-tr":["2254"],"lang-de":["2287"],"lang-es":["2267"],"lang-pt_br":["3149"],"lang-en":["193"],"lang-pt-br":["3149"],"lang-id":["4127"],"\u0430\u0432\u0442\u043e\u0440":["Pedro \u00c1lvares"],"_\u0430\u0432\u0442\u043e\u0440":["field_5e33cab3984d1"],"\u0444\u043e\u0442\u043e":[""],"_\u0444\u043e\u0442\u043e":["field_5e33cbc1984d2"],"hide-in-popular":[""],"_hide-in-popular":["field_5d0c8a5b4fde2"],"mpulseenable_meta_value":["no"],"ytrssenabled_meta_value":["no"],"ytremove_meta_value":["yes"],"ytad1meta":["enabled"],"ytad2meta":["enabled"],"ytad3meta":["enabled"],"ytad4meta":["enabled"],"ytad5meta":["enabled"],"template_meta":["no"],"yzcategory_meta_value":["\u0414\u043e\u043c"],"yzrating_meta_value":["\u041d\u0435\u0442 (\u043d\u0435 \u0434\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445)"],"yzrssenabled_meta_value":["yes"],"saswp_custom_schema_field":[""],"amphtml_featured_image_id":["0"],"amphtml-exclude":["0"],"amphtml-override-title":[""],"amphtml-override-content":[""],"_s2mail":["yes"],"ampforwp_custom_content_editor":[""],"ampforwp_custom_content_editor_checkbox":[null],"ampforwp-amp-on-off":["default"],"_aioseop_description":["App Controle Parental com Mobile Tracker para Manter Filhos Seguros - Find My Kids com GPS Tracker Permite Localizar Telemovel da Crian\u00e7a e Escutar \u00e0 Volta Dela"],"_aioseop_title":["Controlo Parental e GPS Tracker Para Vigiar Filhos"]},"categories":[63,135],"tags":[],"language":[49],"acf":{"custom_title":"","custom_image":null,"custom_alt":"","read_more":null},"aioseo_notices":[],"featured_image_src":"https:\/\/cdn-blog.findmykids.org\/2016\/10\/gps_find.jpg","author_info":{"display_name":"Find My Kids","author_link":"https:\/\/findmykids.org\/blog\/ru\/author\/karpova"},"jetpack_featured_media_url":"https:\/\/cdn-blog.findmykids.org\/2016\/10\/gps_find.jpg","reading_time":"3","_links":{"self":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/2404"}],"collection":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/comments?post=2404"}],"version-history":[{"count":5,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/2404\/revisions"}],"predecessor-version":[{"id":11402,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/2404\/revisions\/11402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media\/16"}],"wp:attachment":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media?parent=2404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/categories?post=2404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/tags?post=2404"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/language?post=2404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}