{"id":56358,"date":"2026-02-16T21:45:31","date_gmt":"2026-02-16T18:45:31","guid":{"rendered":"https:\/\/findmykids.org\/blog\/?p=56358"},"modified":"2026-03-18T16:38:38","modified_gmt":"2026-03-18T13:38:38","slug":"por-que-mienten-los-adolescentes-de-16-anos-y-como-reaccionar","status":"publish","type":"post","link":"https:\/\/findmykids.org\/blog\/es\/por-que-mienten-los-adolescentes-de-16-anos-y-como-reaccionar","title":{"rendered":"\u00bfPor qu\u00e9 mienten los adolescentes de 16 a\u00f1os y c\u00f3mo reaccionar?"},"content":{"rendered":"<p>Los adolescentes rara vez mienten sin raz\u00f3n. A\u00a0diferencia de\u00a0los ni\u00f1os m\u00e1s peque\u00f1os, su\u00a0enga\u00f1o suele estar relacionado con el\u00a0deseo de\u00a0establecer l\u00edmites, protegerse o\u00a0integrarse en\u00a0los dem\u00e1s. Comprender estas razones puede ayudar al\u00a0adolescente a\u00a0apoyarse y\u00a0a\u00a0generar confianza.<\/p>\n<h2>\ud83d\udcca Lo\u00a0que dice la\u00a0investigaci\u00f3n<\/h2>\n<p>A\u00a0esta edad, el\u00a0enga\u00f1o se\u00a0vuelve m\u00e1s complejo y\u00a0reflexivo, y\u00a0sus razones se\u00a0relacionan con el\u00a0autodescubrimiento, los l\u00edmites personales y\u00a0el\u00a0deseo de\u00a0pertenencia.<\/p>\n<p>Seg\u00fan las investigaciones, los adolescentes consideran justificada la\u00a0mentira si\u00a0les ayuda a\u00a0proteger sus l\u00edmites personales y\u00a0mienten con m\u00e1s frecuencia si\u00a0conf\u00edan en\u00a0que su\u00a0enga\u00f1o no\u00a0ser\u00e1 descubierto.<\/p>\n<h2>\ud83d\udd11 Por qu\u00e9 los adolescentes ocultan la\u00a0verdad y\u00a0qu\u00e9 pueden hacer los padres<\/h2>\n<p>A\u00a0medida que los ni\u00f1os crecen, pueden volverse menos abiertos con sus padres. A\u00a0veces parece que un\u00a0adolescente oculta algo o\u00a0evita conversaciones, pero esto es\u00a0parte de\u00a0su\u00a0desarrollo y\u00a0hay razones para mentir.<\/p>\n<p>Los adolescentes mienten porque:<\/p>\n<h3>Protegen su\u00a0espacio personal<\/h3>\n<p>A\u00a0esta edad, los adolescentes valoran m\u00e1s su\u00a0privacidad y\u00a0pueden ocultar cosas para evitar ser vigilados excesivamente.<\/p>\n<p>Qu\u00e9 hacer: Respetar los l\u00edmites personales: \u00abEntiendo que quieras guardarte algunas cosas. Pero siempre te\u00a0escuchar\u00e9 y\u00a0estar\u00e9 aqu\u00ed si\u00a0me\u00a0necesitas\u00bb. Los adolescentes tienen derecho a\u00a0sus secretos: acuerden reglas importantes, pero no\u00a0los presionen.<\/p>\n<h3>Quieren ser independientes<\/h3>\n<p>A\u00a0veces los adolescentes mienten para evadir las restricciones. Por ejemplo, pueden decir que van a\u00a0casa de\u00a0un\u00a0amigo, pero en\u00a0realidad van a\u00a0una fiesta.<\/p>\n<p>Qu\u00e9 hacer: Establecer y\u00a0explicar las reglas: \u00abEntiendo que necesitas libertad, pero mi\u00a0prioridad es\u00a0tu\u00a0seguridad\u00bb. Deseo de\u00a0formar parte de\u00a0un\u00a0grupo<\/p>\n<p>Los adolescentes pueden mentir para encajar o\u00a0proteger a\u00a0sus amigos. Por ejemplo, pueden ocultar la\u00a0verdad para evitar decepcionar a\u00a0un\u00a0amigo o\u00a0revelar el\u00a0secreto de\u00a0otra persona.<\/p>\n<p>Qu\u00e9 hacer: Hablar sobre la\u00a0amistad: \u00abSi\u00a0un\u00a0amigo te\u00a0pide que mientas, piensa si\u00a0te\u00a0est\u00e1 poniendo en\u00a0una situaci\u00f3n dif\u00edcil\u00bb.<\/p>\n<h3>Experimentar con la\u00a0identidad<\/h3>\n<p>Mentir puede ser parte del autodescubrimiento, experimentando con diferentes roles e\u00a0im\u00e1genes.<\/p>\n<p>Qu\u00e9 hacer: Apoyar al\u00a0adolescente en\u00a0su\u00a0b\u00fasqueda: \u00abEntiendo que est\u00e1s tratando de\u00a0descubrir qui\u00e9n eres. Recuerda, siempre estoy aqu\u00ed para\u00a0ti\u00bb.<\/p>\n<h3>Miedo al\u00a0juicio<\/h3>\n<p>Los adolescentes pueden ocultar sus fracasos para evitar ser juzgados por adultos o\u00a0compa\u00f1eros.<\/p>\n<p>Qu\u00e9 hacer: Crear un\u00a0ambiente donde el\u00a0adolescente se\u00a0sienta c\u00f3modo diciendo la\u00a0verdad: \u00abPuedes decirme lo\u00a0que sea. No\u00a0te\u00a0juzgar\u00e9\u00bb.<\/p>\n<p>Los adolescentes no\u00a0mienten por despecho ni\u00a0porque sean \u00abmalos\u00bb, sino que buscan su\u00a0lugar en\u00a0el\u00a0mundo. Mu\u00e9strales que la\u00a0honestidad los hace m\u00e1s fuertes y\u00a0siempre el\u00f3gialos por decir la\u00a0verdad.<\/p>\n\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"56358\"\n\t\t\t\t\tdata-ulike-nonce=\"db3f2b3b18\"\n\t\t\t\t\tdata-ulike-type=\"likeThis\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-disable-pophover=\"0\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_likethis_56358\"><\/button><\/div><\/div>\n\t","protected":false},"excerpt":{"rendered":"<p>Los adolescentes rara vez mienten sin raz\u00f3n. A\u00a0diferencia de\u00a0los ni\u00f1os m\u00e1s peque\u00f1os, su\u00a0enga\u00f1o suele estar&#8230;<\/p>\n","protected":false},"author":47,"featured_media":52542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"layf_related_links":[""],"layf_exclude_from_feed":["1"],"classic-editor-remember":["classic-editor"],"_edit_lock":["1773841174:1"],"_edit_last":["1"],"_thumbnail_id":["52542"],"mpulseenable_meta_value":["no"],"yzcategory_meta_value":["\u0414\u043e\u043c"],"yzrating_meta_value":["\u041d\u0435\u0442 (\u043d\u0435 \u0434\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445)"],"yzrssenabled_meta_value":["no"],"_s2mail":["yes"],"_ez-toc-disabled":[""],"_ez-toc-insert":[""],"_ez-toc-header-label":[""],"_ez-toc-device-target":[""],"_ez-toc-alignment":["none"],"_ez-toc-heading-levels":["a:0:{}"],"_ez-toc-alttext":[""],"_ez-toc-visibility_hide_by_default":[""],"_ez-toc-hide_counter":[""],"_ez-toc-exclude":[""],"_ez-toc-word_count_limit":["0"],"_ez-toc-position-specific":[""],"\u0430\u0432\u0442\u043e\u0440":["El equipo editorial de Findmykids"],"_\u0430\u0432\u0442\u043e\u0440":["field_5e33cab3984d1"],"\u0444\u043e\u0442\u043e":["3272"],"_\u0444\u043e\u0442\u043e":["field_5e33cbc1984d2"],"hide-in-popular":[""],"_hide-in-popular":["field_5d0c8a5b4fde2"],"custom_title":[""],"_custom_title":["field_67cfbde67c007"],"custom_image":[""],"_custom_image":["field_67d012de223ac"],"custom_alt":[""],"_custom_alt":["field_67d012f6223ad"],"read_more":[""],"_read_more":["field_67d0130e223ae"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"saswp_custom_schema_field":[""]},"categories":[668],"tags":[],"language":[52],"acf":{"custom_title":"","custom_image":"","custom_alt":"","read_more":""},"aioseo_notices":[],"featured_image_src":"https:\/\/cdn-blog.findmykids.org\/2025\/04\/Pochemu-x-letnij-podrostok-vryot-i-kak-reagirovat_1200x640_statya-1.png","author_info":{"display_name":"El equipo editorial de Findmykids","author_link":"https:\/\/findmykids.org\/blog\/ru\/author\/el-equipo-editorial-de-findmykids"},"jetpack_featured_media_url":"https:\/\/cdn-blog.findmykids.org\/2025\/04\/Pochemu-x-letnij-podrostok-vryot-i-kak-reagirovat_1200x640_statya-1.png","reading_time":"2","_links":{"self":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/56358"}],"collection":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/comments?post=56358"}],"version-history":[{"count":4,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/56358\/revisions"}],"predecessor-version":[{"id":57935,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/56358\/revisions\/57935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media\/52542"}],"wp:attachment":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media?parent=56358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/categories?post=56358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/tags?post=56358"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/language?post=56358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}