{"id":8263,"date":"2020-02-26T15:19:39","date_gmt":"2020-02-26T12:19:39","guid":{"rendered":"\/blog\/?p=8263"},"modified":"2021-06-21T13:45:59","modified_gmt":"2021-06-21T10:45:59","slug":"como-parar-de-se-preocupar-com-os-filhos-e-virar-uma-boa-mae","status":"publish","type":"post","link":"https:\/\/findmykids.org\/blog\/pt-br\/como-parar-de-se-preocupar-com-os-filhos-e-virar-uma-boa-mae","title":{"rendered":"Como parar de se preocupar com os filhos e virar uma boa m\u00e3e"},"content":{"rendered":"<p>A sensa\u00e7\u00e3o de preocupa\u00e7\u00e3o pelo filho acontece com todas as m\u00e3es. H\u00e1 muitas raz\u00f5es para o nervosismo. Infelizmente, fen\u00f4menos como terrorismo, pedofilia ou sequestros, os quais antes s\u00f3 se via em filmes, viraram parte da nossa realidade. Preocupamo-nos com a sa\u00fade de nossos filhos, ficamos aflitos ao deix\u00e1-los sozinhos em casa ou na rua, tememos influ\u00eancias negativas e assim por diante\u2026 a lista \u00e9 grande. Mas a preocupa\u00e7\u00e3o constante pelo seu filho ou sua filha pode levar a depress\u00e3o ou ansiedade. Pode at\u00e9 mesmo causar um colapso nervoso na m\u00e3e. E isto sem nem falarmos das consequ\u00eancias que os cuidados excessivos da parte dos pais podem causar na crian\u00e7a.<\/p>\n<p>Se voc\u00ea quer aprender a lidar com a ansiedade constante com seu filho, a encarar os seus medos e descobrir onde eles come\u00e7am \u2013 se voc\u00ea quer virar uma boa m\u00e3e e desfrutar da maternidade, ent\u00e3o esse artigo \u00e9 para voc\u00ea.<\/p>\n<h2>Conte\u00fados:<\/h2>\n<ul class=\"contents\">\n<li><a href=\"#Enfrente\">Enfrente os seus medos: as causas da ansiedade materna<\/a><\/li>\n<li><a href=\"#Qual\">Qual \u00e9 o perigo da ansiedade constante pela crian\u00e7a?<\/a>\n<ul>\n<li><a href=\"#O\">O que espera uma m\u00e3e ansiosa?<\/a><\/li>\n<li><a href=\"#E\">E o que espera a crian\u00e7a?<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"#Lidando\">Lidando com a ansiedade: conselhos de um especialista<\/a>\n<ul>\n<li><a href=\"#Como\">Como virar uma m\u00e3e calma e boa?<\/a><\/li>\n<li><a href=\"#A\">A m\u00e3e ideal: quem \u00e9 ela?<\/a><\/li>\n<li><a href=\"#Regras\">Regras e h\u00e1bitos di\u00e1rios para uma boa m\u00e3e<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"Enfrente\">Enfrente os seus medos: as causas da ansiedade materna<\/h2>\n<div id=\"attachment_6955\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6955\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6955\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-perezhivaniya.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6955\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Quando a mulher fica gr\u00e1vida e espera dar \u00e0 luz, ela est\u00e1 sempre rodeada da aten\u00e7\u00e3o e dos cuidados de seus parentes. Ela se sente importante e necess\u00e1ria. Mas quando o beb\u00ea nasce, tudo muda dramaticamente. As necessidades do beb\u00ea v\u00eam antes e a mulher esquece de si mesma: sobra pouco tempo para comer, dormir ou tomar banho. Ela passa a maior parte do tempo sozinha com a crian\u00e7a, deixando o marido trabalhar para sustent\u00e1-los.<\/p>\n<p>Com isso tudo, n\u00e3o \u00e9 surpreendente que muitas m\u00e3es \u2013 especialmente as mais novas \u2013 acumulem fadiga e frustra\u00e7\u00f5es. Elas come\u00e7am a perder a paci\u00eancia com a crian\u00e7a e com o marido e depois sentem remorso por se comportar como uma m\u00e3e ruim. Esta tend\u00eancia vai gerando uma base perigosamente forte para a ansiedade e o medo.<\/p>\n<p>Os medos que a maioria das m\u00e3es sente:<\/p>\n<ul>\n<li>preocupa\u00e7\u00e3o com a vida e sa\u00fade da crian\u00e7a, medo de perd\u00ea-la;<\/li>\n<li>medo de machucar acidentalmente a a crian\u00e7a;<\/li>\n<li>medo de ser uma m\u00e3e ruim, tanto aos olhos da crian\u00e7a quanto dos outros;<\/li>\n<li>medo de ser julgada por m\u00e3es mais experientes;<\/li>\n<li>medo de ficar isolada socialmente por causa de uma longa licen\u00e7a-maternidade;<\/li>\n<li>medo de piorar o relacionamento com o marido.<\/li>\n<\/ul>\n<p>A ansiedade excessiva pelo bem-estar da crian\u00e7a tamb\u00e9m \u00e9 aumentada pelos fen\u00f4menos da vida moderna, como por exemplo:<\/p>\n<ul>\n<li>os \u00edndices elevados de crimes, casos frequentes de sequestros infantis;<\/li>\n<li>a popularidade de drogas, \u00e1lcool e cigarros entre jovens, bem como um in\u00edcio precoce de atividades sexuais;<\/li>\n<li>a f\u00e1cil disponibilidade de todo tipo de informa\u00e7\u00e3o e conte\u00fado visual na Internet;<\/li>\n<li>o aparecimento de \u00abclubes da morte\u00bb e \u00abseitas suicidas\u00bb nas redes sociais.<\/li>\n<\/ul>\n<div id=\"attachment_6949\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6949\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6949\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/girl-4566074_1920.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6949\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Assim, a m\u00e3e preocupada come\u00e7a a controlar cada passo e respira\u00e7\u00e3o da crian\u00e7a, tentando estar sempre com ela: primeiro em casa e depois na pr\u00e9-escola e na escola. Com isso, ela nega a si mesma e a sua fam\u00edlia uma vida normal e completa.<\/p>\n<p class=\"warning\">Caras mam\u00e3es, lembrem-se! A sensa\u00e7\u00e3o de afli\u00e7\u00e3o pela crian\u00e7a \u00e9 um dos componentes mais essenciais do instinto materno. Toda m\u00e3e se preocupa com seus filhos e procura proteg\u00ea-los dos perigos do mundo.<\/p>\n<p>Voc\u00ea n\u00e3o precisa lutar com os seus medos \u2013 \u00e9 preciso aceit\u00e1-los e admitir: \u00abSim, eu me preocupo, sim, com meu filho, mas n\u00e3o posso ficar constantemente restringindo e proibindo\u00bb. Voc\u00ea tamb\u00e9m precisa entender as raz\u00f5es pelas quais se sente aflita, e dizer a si mesma: \u00abA minha preocupa\u00e7\u00e3o pode ser explicada \u2013 esse \u00e9 o meu primeiro filho e tenho medo de acabar sendo uma m\u00e3e ruim\u00bb.<\/p>\n<p>Desta forma, ser\u00e1 muito mais f\u00e1cil de conquistar os seus medos.<\/p>\n<p>\u00c9 importante diferenciar entre uma preocupa\u00e7\u00e3o normal pela crian\u00e7a e a ansiedade neur\u00f3tica e obsessiva pela vida e sa\u00fade da crian\u00e7a que afeta negativamente a fam\u00edlia toda.<\/p>\n<p>As m\u00e3es mais pass\u00edveis de ser afetadas por uma ansiedade neur\u00f3tica s\u00e3o:<\/p>\n<ul>\n<li>m\u00e3es que equiparam o nascimento da crian\u00e7a com o significado da pr\u00f3pria vida;<\/li>\n<li>m\u00e3es que vivenciaram a morte de uma crian\u00e7a ou de um parente pr\u00f3ximo;<\/li>\n<li>m\u00e3es que tiveram um parto complicado ou cujo beb\u00ea esteve em risco de vida nos primeiros meses de vida.<\/li>\n<\/ul>\n<p>Se voc\u00ea perceber que a ansiedade pelo seu filho chegou a um ponto alarmante, que colapsos nervosos est\u00e3o acontecendo cada vez mais e que a maternidade deixou de ser uma fonte de emo\u00e7\u00f5es positivas para voc\u00ea, ent\u00e3o est\u00e1 na hora de contatar um especialista \u2013 o quanto antes, melhor.<\/p>\n<h2 id=\"Qual\">Qual \u00e9 o perigo da ansiedade constante pela crian\u00e7a?<\/h2>\n<div id=\"attachment_6953\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6953\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6953\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-1024x682.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-1024x682.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-808x538.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/the-offence-2048413_1280.jpg 1280w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6953\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Agora vamos falar sobre as consequ\u00eancias que o seu medo e ansiedade constantes podem ter para o seu filho.<\/p>\n<h3 id=\"O\">O que espera uma m\u00e3e ansiosa?<\/h3>\n<p>Viver em ansiedade e estresse constantes afeta negativamente a sa\u00fade f\u00edsica e mental da m\u00e3e. Doen\u00e7as cr\u00f4nicas se agravam. Quando unidas \u00e0 depress\u00e3o, irritabilidade e colapsos nervosos, isso tudo pode levar a pensamentos suicidas, nos piores casos.<\/p>\n<p>A depress\u00e3o p\u00f3s-parto (DPP) atinge mais de uma em cada quatro mulheres no Brasil, conforme mostrou um estudo realizado pela pesquisadora Mariza Theme, da Escola Nacional de Sa\u00fade P\u00fablica Sergio Arouca (Ensp\/Fiocruz). Quanto mais jovem a m\u00e3e, maior a chance da DPP \u2013 um estudo da USP de Ribeir\u00e3o Preto detectou que, entre m\u00e3es jovens de 12 a 19 anos, mais da metade apresentava sintomas de DPP.\u2800<\/p>\n<p>Uma m\u00e3e com ansiedade ou depress\u00e3o p\u00f3s-parto vai parando de ver amigos e visitar parentes. Os seus relacionamentos sociais v\u00e3o sendo destru\u00eddos. Desta forma, a m\u00e3e acaba por se encontrar isolada da sociedade.<\/p>\n<p>O relacionamento com o marido tamb\u00e9m pode ser prejudicado. Conforme a crian\u00e7a se torna o centro de aten\u00e7\u00e3o no mundo da mulher, o marido pode sentir que n\u00e3o est\u00e1 mais recebendo suficiente amor, carinho e aten\u00e7\u00e3o da esposa. Que tipo de solu\u00e7\u00e3o o homem tem em situa\u00e7\u00f5es assim? O que frequentemente acontece \u00e9 que ele ou se concentra mais no trabalho, deixando a fam\u00edlia virar segunda prioridade, ou quebra as promessas do casamento, procurando receber carinho e aten\u00e7\u00e3o de outra pessoa.<\/p>\n<h3 id=\"E\">E o que espera a crian\u00e7a?<\/h3>\n<div id=\"attachment_5902\" style=\"width: 759px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5902\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-5902\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-1024x683.jpg\" alt=\"\" width=\"749\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-392x262.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika-1232x822.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/isterika.jpg 1280w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><p id=\"caption-attachment-5902\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Se a mulher cresceu em uma atmosfera de constantes restri\u00e7\u00f5es e proibi\u00e7\u00f5es associadas com a ansiedade cada vez maior de sua m\u00e3e, o mais prov\u00e1vel \u00e9 que ela tamb\u00e9m crie os seus filhos desta forma. Isto se deve ao fato de que na mente dela se forma um estere\u00f3tipo de comportamento maternal baseado naquilo que ela sempre presenciou na pr\u00f3pria fam\u00edlia.<\/p>\n<p>Se a m\u00e3e fica constantemente dizendo como o mundo \u00e9 perigoso e como as pessoas s\u00e3o ruins, n\u00e3o \u00e9 de surpreender que a crian\u00e7a comece a sofrer de neuroses em pouco tempo.<\/p>\n<p class=\"warning\">A ansiedade materna excessiva pode levar a uma redu\u00e7\u00e3o no desenvolvimento f\u00edsico e mental da crian\u00e7a.<\/p>\n<p>Proibi\u00e7\u00f5es constantes de atividades f\u00edsicas, do tipo \u00abN\u00e3o suba nessa \u00e1rvore, voc\u00ea vai cair\u00bb, impedem a crian\u00e7a de desenvolver aspectos f\u00edsicos essenciais. Roupas quentes demais, monitoramento excessivo da temperatura do ambiente e da \u00e1gua \u2013 isso tudo enfraquece a imunidade natural da crian\u00e7a. As restri\u00e7\u00f5es de sa\u00eddas com amigos que s\u00e3o considerados \u00abm\u00e1 influ\u00eancia\u00bb pela m\u00e3e destroem as tend\u00eancias das intera\u00e7\u00f5es sociais da crian\u00e7a e impedem o desenvolvimento da capacidade de comunica\u00e7\u00e3o dela.<\/p>\n<p>Uma crian\u00e7a que \u00e9 \u00abcuidada demais\u00bb, uma \u00abfilhinha de mam\u00e3e\u00bb, pode ser ridicularizada pelos colegas e sofrer de <em>bullying<\/em>. Isto leva a uma baixa autoestima, gerando preocupa\u00e7\u00f5es, seclus\u00e3o e d\u00favidas em rela\u00e7\u00e3o a si mesma.<\/p>\n<p>Na maioria dos casos, a pessoa que na inf\u00e2ncia foi rodeada de aten\u00e7\u00f5es excessivas da parte dos pais procura compensar e escapar da influ\u00eancia deles assim que cresce: \u00e9 comum que um jovem com um hist\u00f3rico desse tipo comece a experimentar com bebida e subst\u00e2ncias ilegais, andando na companhia de tipos ruins, etc. A pessoa pode at\u00e9 mesmo acabar se casando cedo s\u00f3 para escapar dos pais. Infelizmente, nem todos esses casos t\u00eam final feliz.<\/p>\n<table style=\"height: 160px; background-color: white !important; max-width: 600px !important;\">\n<tbody>\n<tr>\n<td style=\"background-color: white !important; border: 0px; padding: 0 10px 0 0 !important; margin: 0px;\" rowspan=\"2\" width=\"160\"><span style=\"color: #ffffff;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-678\" src=\"https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview.png\" alt=\"fmk_05_andr_1024_preview\" width=\"160\" height=\"160\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview.png 1077w, https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview-808x808.png 808w, https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview-392x392.png 392w, https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview-768x768.png 768w, https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview-1024x1024.png 1024w, https:\/\/cdn-blog.findmykids.org\/2017\/01\/fmk_05_andr_1024_preview-300x300.png 300w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/><\/span><\/td>\n<td style=\"background-color: white !important; border: 0px; padding: 0px;\" colspan=\"2\" width=\"550\">\n<h5 style=\"padding: 0 !important; margin: 0 !important;\"><strong><b>Instale o app Findmykids<\/b><\/strong><\/h5>\n<p><span style=\"font-weight: 400;\">Confira se seus filhos est\u00e3o bem e pare de se preocupar!<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border: 0px; padding: 0 10px 0 0; max-height: 50px !important;\" width=\"157\"><a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=como-parar-de-se-preocupar-com-os-filhos-e-virar-uma-boa-mae\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-679\" src=\"https:\/\/cdn-blog.findmykids.org\/2017\/01\/appstore_button.png\" alt=\"snimok-yekrana-2017-11-07-v-19-53-51\" width=\"532\" height=\"133\" \/><\/a><\/td>\n<td style=\"border: 0px; padding: 0px; max-height: 50px !important;\" width=\"150\"><a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=como-parar-de-se-preocupar-com-os-filhos-e-virar-uma-boa-mae\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-680\" src=\"https:\/\/cdn-blog.findmykids.org\/2017\/01\/google-play-badge.jpg\" alt=\"snimok-yekrana-2017-11-07-v-19-54-01\" width=\"528\" height=\"132\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 id=\"Lidando\">Lidando com a ansiedade: conselhos de um especialista<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6952\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-1024x661.jpg\" alt=\"\" width=\"774\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-1024x661.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-150x97.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-300x194.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-768x496.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-600x388.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-200x129.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-808x522.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-392x253.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920-1232x796.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/sky-2667455_1920.jpg 1920w\" sizes=\"(max-width: 774px) 100vw, 774px\" \/><\/p>\n<h3 id=\"E\">Como virar uma m\u00e3e calma e boa?<\/h3>\n<p>Em primeiro lugar, decida para quem voc\u00ea quer ser uma boa m\u00e3e: para seus filhos ou para os outros verem. Voc\u00ea pode colocar fotos alegres da fam\u00edlia nas redes sociais, dizer para os amigos como voc\u00ea ama o seu filho e comprar montes de brinquedos para ele. Mas ao mesmo tempo voc\u00ea pode estar impondo press\u00e3o psicol\u00f3gica na crian\u00e7a, perdendo a paci\u00eancia sem boa raz\u00e3o, limitando a liberdade dela e proibindo qualquer forma de manifesta\u00e7\u00e3o independente.<\/p>\n<p class=\"warning\">N\u00e3o d\u00e1 para nascer j\u00e1 sendo uma boa m\u00e3e. Esse \u00e9 um processo do dia a dia: um processo exaustivo, que \u00e0s vezes leva a pessoa a duvidar de se virar m\u00e3e foi uma boa escolha \u2013 mas que no final tem muitas recompensas. \u00c9 uma curva de aprendizado que vai das primeiras noites insones e do choro constante at\u00e9 o primeiro sorriso, a primeira nota 10 na escola, o primeiro \u00abEu amo voc\u00ea, mam\u00e3e\u00bb.<\/p>\n<p>Por isso, \u00e9 importante para toda m\u00e3e n\u00e3o s\u00f3 ser boa, mas equilibrada. O que est\u00e1 contido na no\u00e7\u00e3o de \u00abequilibrada\u00bb? Isto significa manter um equil\u00edbrio entre os problemas do dia a dia e o relaxamento; entre cuidar da crian\u00e7a e dar aten\u00e7\u00e3o ao marido; entre as quest\u00f5es de fam\u00edlia e o pr\u00f3prio tempo pessoal; entre a ansiedade pela crian\u00e7a e o desejo de estimular o progresso e desenvolvimento dela.<\/p>\n<div id=\"attachment_6950\" style=\"width: 828px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6950\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6950\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-1024x626.jpg\" alt=\"\" width=\"818\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-1024x626.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-150x92.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-300x183.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-768x469.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-600x367.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-200x122.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-808x494.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-392x239.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920-1232x753.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/holidays-3384160_1920.jpg 1920w\" sizes=\"(max-width: 818px) 100vw, 818px\" \/><p id=\"caption-attachment-6950\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Voc\u00ea est\u00e1 cansada das eternas tarefas de casa e de colapsos nervosos que seu filho e marido presenciam? Chame os av\u00f3s e amigos para ajud\u00e1-la: v\u00e1 para um sal\u00e3o de beleza, assista a um concerto ou saia com o marido \u2013 qualquer lugar serve, mas o importante \u00e9 restaurar o equil\u00edbrio. Est\u00e1 preocupada pensando que a crian\u00e7a pode cair de um escorregador ou passar frio do lado de fora da pr\u00e9-escola? Diga \u00abn\u00e3o\u00bb para as suas emo\u00e7\u00f5es e comece a avaliar a emo\u00e7\u00e3o com clareza: o escorregador n\u00e3o \u00e9 t\u00e3o alto assim e al\u00e9m disso o seu filho j\u00e1 sabe segurar nos lados e escorregar direito; ele est\u00e1 vestindo roupas quentes e as crian\u00e7as est\u00e3o sempre brincando do lado de fora da pr\u00e9-escola, o que quer dizer que ele n\u00e3o vai sentir frio.<\/p>\n<p class=\"warning\">Procure estabelecer equil\u00edbrio no relacionamento com a crian\u00e7a, com o marido e com outros: n\u00e3o deixe o medo e a ansiedade envenenarem a sua vida.<\/p>\n<p>Se a ansiedade se manifestou de repente e voc\u00ea sente que est\u00e1 come\u00e7ando a entrar em p\u00e2nico quando v\u00eam aqueles pensamentos de algo terr\u00edvel que pode acontecer com a crian\u00e7a, as seguintes t\u00e9cnicas podem ajudar:<\/p>\n<ul>\n<li>feche os olhos, inspire e exale fundo por tr\u00eas minutos, concentrando-se na respira\u00e7\u00e3o;<\/li>\n<li>dedique-se a algum tipo de atividade f\u00edsica, at\u00e9 mesmo a tarefas de casa;<\/li>\n<li>compartilhe o que est\u00e1 sentindo com o seu marido, parentes ou amigos pr\u00f3ximos;<\/li>\n<li>depois de se acalmar, fa\u00e7a as seguintes perguntas a si mesma: a crian\u00e7a est\u00e1 em perigo nesse momento ou ser\u00e1 que isso est\u00e1 s\u00f3 na minha cabe\u00e7a? Isso \u00e9 assustador de verdade? O que posso fazer para evitar isso?<\/li>\n<\/ul>\n<h3 id=\"A\">A m\u00e3e ideal: quem \u00e9 ela?<\/h3>\n<div id=\"attachment_6889\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6889\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6889\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/How-To-Raise-A-Body-Positive-Kid-1232x821.jpg 1232w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6889\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Qual imagem lhe vem \u00e0 cabe\u00e7a quando voc\u00ea ouve esta pergunta? Uma m\u00e3e que nunca se irrita e grita com a crian\u00e7a? Ou a m\u00e3e cujo filho est\u00e1 sempre bem vestido e penteado? Ou talvez a m\u00e3e que s\u00f3 prepara alimentos saud\u00e1veis e cuja casa est\u00e1 sempre limpa e brilhante?<\/p>\n<p>Imediatamente, uma segunda pergunta surge: ser\u00e1 que sobra tempo para uma m\u00e3e assim cuidar de si mesma, de seus pr\u00f3prios desejos e necessidades? Ser\u00e1 que ela cuida da pr\u00f3pria sa\u00fade e do pr\u00f3prio corpo, de seus assuntos pessoais? Provavelmente n\u00e3o. Ela simplesmente n\u00e3o tem tempo para isto. A partir da\u00ed, pode ser tirada uma conclus\u00e3o direta: a m\u00e3e perfeita \u00e9 a mulher que se concentra inteiramente em criar o filho, que abandonou o relacionamento com o marido e que est\u00e1 atormentada pelo trabalho e pelas tarefas dom\u00e9sticas ao mesmo tempo.<\/p>\n<p class=\"warning\">Ent\u00e3o voc\u00ea ainda quer ser uma m\u00e3e perfeita? Vamos substituir a frase \u00abm\u00e3e perfeita\u00bb pela frase \u00abuma boa m\u00e3e para seu filho\u00bb.<\/p>\n<p>Mas o que uma boa m\u00e3e pode fazer por seu filho? Bem, acontece que a lista \u00e9 bem longa. Uma boa m\u00e3e:<\/p>\n<ul>\n<li>\u00c9 justa. Ela s\u00f3 d\u00e1 broncas na crian\u00e7a por boas raz\u00f5es;<\/li>\n<li>Preocupa-se com a crian\u00e7a, mas permite que esta demonstre sua independ\u00eancia;<\/li>\n<li>Gosta de passar tempo com os filhos;<\/li>\n<li>Ouve o filho com aten\u00e7\u00e3o e est\u00e1 sempre pronta a ajudar;<\/li>\n<li>Tem orgulho da crian\u00e7a e de suas conquistas;<\/li>\n<li>N\u00e3o esconde os sentimentos do filho e n\u00e3o subestima as preocupa\u00e7\u00f5es dele;<\/li>\n<li>N\u00e3o procura estar com o filho 24 horas por dia e n\u00e3o limita a liberdade dele;<\/li>\n<li>Ama a crian\u00e7a independentemente do jeito dela: gordinha, magrinha, um pouco pregui\u00e7osa, mais reservada\u2026<\/li>\n<li>Nunca se refere ao marido, aos pais ou a outros parentes de forma negativa ao falar com a crian\u00e7a.<\/li>\n<\/ul>\n<h3 id=\"Regras\">Regras e h\u00e1bitos di\u00e1rios para uma boa m\u00e3e<\/h3>\n<div id=\"attachment_6947\" style=\"width: 759px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6947\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6947\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-1024x684.jpg\" alt=\"\" width=\"749\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-1024x684.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-768x513.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-600x401.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-200x134.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-392x262.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/12\/ben-white-08swtCO0Syg-unsplash-1232x822.jpg 1232w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><p id=\"caption-attachment-6947\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<ol>\n<li>Diga ao seu filho que o ama e fa\u00e7a isso com frequ\u00eancia. Demonstre o seu carinho com beijos e abra\u00e7os.<\/li>\n<li>Mostre interesse na vida do filho, nas tarefas di\u00e1rias, nas derrotas e conquistas dele.<\/li>\n<li>Elogie a crian\u00e7a por seus sucessos e d\u00ea \u00eanfase para as conquistas dela.<\/li>\n<li>D\u00ea algumas tarefas para a crian\u00e7a, como regar as plantas, lavar os pratos ou espanar os m\u00f3veis.<\/li>\n<li>Toda noite, ache um momento para passar a s\u00f3s com a crian\u00e7a. Ponha de lado todos os aparelhos eletr\u00f4nicos, desligue computadores ou TVs e leia uma hist\u00f3ria para a crian\u00e7a dormir ou jogue um jogo calmo com ela.<\/li>\n<li>Pe\u00e7a a opini\u00e3o da crian\u00e7a em rela\u00e7\u00e3o a quest\u00f5es familiares.<\/li>\n<li>Pe\u00e7a ajuda \u00e0 crian\u00e7a e sempre agrade\u00e7a depois.<\/li>\n<li>Se voc\u00ea estiver aborrecida com alguma coisa, n\u00e3o esconda os sentimentos da crian\u00e7a e permita que ela tamb\u00e9m se comporte com sinceridade, sendo ela mesma.<\/li>\n<li>Surpreenda o seu filho com maior frequ\u00eancia. Sempre h\u00e1 espa\u00e7o para milagres na vida di\u00e1ria.<\/li>\n<li>Encontre os amigos do seu filho. Mesmo que voc\u00ea n\u00e3o goste especialmente deles, n\u00e3o fale sobre eles de forma negativa a fim de n\u00e3o ferir a crian\u00e7a.<div id=\"attachment_5342\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5342\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-5342\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-1024x666.png\" alt=\"\" width=\"768\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-1024x666.png 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-150x98.png 150w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-300x195.png 300w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-768x500.png 768w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-808x526.png 808w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-392x255.png 392w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1-1232x802.png 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/veselie-1-1.png 1357w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><p id=\"caption-attachment-5342\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div><\/li>\n<li>Permita-se fazer brincadeiras e rir com a crian\u00e7a.<\/li>\n<li>Permita que a crian\u00e7a tome decis\u00f5es aut\u00f4nomas sobre a pr\u00f3pria vida.<\/li>\n<li>Se voc\u00ea prometeu algo ao seu filho, mantenha a promessa. Assim ele tamb\u00e9m aprender\u00e1 a sempre manter a palavra.<\/li>\n<li>Preserve cuidadosamente todos os presentes que a crian\u00e7a fez para voc\u00ea. Comunique a ela que tudo que \u00e9 criado pela humanidade tem seu valor.<\/li>\n<li>Procure tomar o caf\u00e9 da manh\u00e3, almo\u00e7ar e jantar em fam\u00edlia.<\/li>\n<li>Tenha alguns rituais de fam\u00edlia. Por exemplo, \u00abfestas de pijamas\u00bb, quando a m\u00e3e, o pai e a crian\u00e7a assistem de noite a um desenho ou filme selecionado por um dos membros da fam\u00edlia. Pode ser uma boa ideia fazer pipoca, preparar chocolate e outros doces com anteced\u00eancia, ou preparar algo em conjunto com todos os membros da fam\u00edlia.<\/li>\n<li>Se voc\u00ea n\u00e3o consegue fazer com que a crian\u00e7a complete uma tarefa, transforme a tarefa em uma brincadeira. Por exemplo, para ensinar o seu filho a se vestir rapidamente, brinque de bombeiro que foi chamado para apagar um inc\u00eandio.<\/li>\n<li>Seja uma boa amiga para o seu filho. Converse com ele sobre os seus interesses e sonhos e assim ele se sentir\u00e1 \u00e0 vontade de compartilhar os dele.<\/li>\n<\/ol>\n<p>Todos n\u00f3s nos preocupamos com os nossos filhos \u2013 nisso n\u00e3o h\u00e1 nada de errado. Os seus filhos est\u00e3o s\u00f3 come\u00e7ando a viver e muitas vezes o universo os submeter\u00e1 a testes e provas. \u00c9 imposs\u00edvel prever e impedir problemas em cada fase da vida da crian\u00e7a. Mas tampouco \u00e9 necess\u00e1rio fazer isso. A crian\u00e7a deve seguir o pr\u00f3prio caminho e tornar-se aut\u00f4noma e independente. N\u00e3o deixe que os seus medos a transformem, de uma m\u00e3e terna e carinhosa, em uma mulher inquieta e infeliz. Lembre-se de cuidar de si mesma e de seus filhos!<\/p>\n<p><div id=\"attachment_3506\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3506\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3506\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/05\/brazilian-banner-fmk.jpg\" alt=\"brazilian banner fmk\" width=\"620\" height=\"305\" \/><p id=\"caption-attachment-3506\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div><br \/>\n<a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=como-parar-de-se-preocupar-com-os-filhos-e-virar-uma-boa-mae\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-1578 size-full\" src=\"https:\/\/cdn-blog.findmykids.org\/2018\/09\/AppStore_GooglePlay_small.png\" alt=\"\" width=\"400\" height=\"84\" \/><\/a><\/p>\n\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"8263\"\n\t\t\t\t\tdata-ulike-nonce=\"aed1ea71e2\"\n\t\t\t\t\tdata-ulike-type=\"likeThis\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-disable-pophover=\"0\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_likethis_8263\"><\/button><span class=\"count-box\">1<\/span>\t\t\t<\/div><\/div>\n\t","protected":false},"excerpt":{"rendered":"<p>A sensa\u00e7\u00e3o de preocupa\u00e7\u00e3o pelo filho acontece com todas as m\u00e3es. H\u00e1 muitas raz\u00f5es para&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"classic-editor-remember":["classic-editor"],"_edit_lock":["1624272221:4"],"_edit_last":["4"],"mpulseenable_meta_value":["no"],"ytrssenabled_meta_value":["no"],"ytremove_meta_value":["yes"],"ytad1meta":["enabled"],"ytad2meta":["enabled"],"ytad3meta":["enabled"],"ytad4meta":["enabled"],"ytad5meta":["enabled"],"template_meta":["no"],"yzcategory_meta_value":["\u0414\u043e\u043c"],"yzrating_meta_value":["\u041d\u0435\u0442 (\u043d\u0435 \u0434\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445)"],"yzrssenabled_meta_value":["yes"],"_s2mail":["yes"],"amphtml_featured_image_id":["0"],"amphtml-exclude":["0"],"amphtml-override-title":[""],"amphtml-override-content":[""],"\u0430\u0432\u0442\u043e\u0440":["Maria Clara Cabreira "],"_\u0430\u0432\u0442\u043e\u0440":["field_5e33cab3984d1"],"\u0444\u043e\u0442\u043e":[""],"_\u0444\u043e\u0442\u043e":["field_5e33cbc1984d2"],"hide-in-popular":[""],"_hide-in-popular":["field_5d0c8a5b4fde2"],"_thumbnail_id":["6957"],"lang-en":["7499"],"lang-ru":["6869"],"saswp_custom_schema_field":[""],"_liked":["1"],"ampforwp_custom_content_editor":[""],"ampforwp_custom_content_editor_checkbox":[null],"ampforwp-amp-on-off":["default"],"layf_related_links":[""],"layf_exclude_from_feed":["0"],"_aioseop_description":["Se voc\u00ea quer aprender a lidar com a constante ansiedade pela crian\u00e7a, descubra as raz\u00f5es para os medos que sente e vire uma boa m\u00e3e que sabe desfrutar da maternidade."],"_aioseop_title":["Medos maternos e ansiedade das m\u00e3es: como lidar com preocupa\u00e7\u00f5es comuns para m\u00e3es"]},"categories":[107],"tags":[],"language":[62],"acf":{"custom_title":"","custom_image":null,"custom_alt":"","read_more":null},"aioseo_notices":[],"featured_image_src":"https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-strakhi.jpg","author_info":{"display_name":"Find My Kids","author_link":"https:\/\/findmykids.org\/blog\/ru\/author\/karpova"},"jetpack_featured_media_url":"https:\/\/cdn-blog.findmykids.org\/2019\/12\/Materinskie-strakhi.jpg","reading_time":"11","_links":{"self":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/8263"}],"collection":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/comments?post=8263"}],"version-history":[{"count":13,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/8263\/revisions"}],"predecessor-version":[{"id":22452,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/8263\/revisions\/22452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media\/6957"}],"wp:attachment":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media?parent=8263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/categories?post=8263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/tags?post=8263"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/language?post=8263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}