{"id":9516,"date":"2020-04-16T14:06:30","date_gmt":"2020-04-16T11:06:30","guid":{"rendered":"\/blog\/?p=9516"},"modified":"2021-06-21T13:42:31","modified_gmt":"2021-06-21T10:42:31","slug":"criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras","status":"publish","type":"post","link":"https:\/\/findmykids.org\/blog\/pt-br\/criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras","title":{"rendered":"Crian\u00e7as problem\u00e1ticas: o que est\u00e1 escondido por tr\u00e1s de sua desobedi\u00eancia e birras?"},"content":{"rendered":"<p>\u00abInquieta, travessa, mal educada, em suma, uma crian\u00e7a problem\u00e1tica\u00bb. Ouvimos essas palavras com muita frequ\u00eancia de nossos pais e professores! As crian\u00e7as problem\u00e1ticas tornam-se o \u00abpesadelo\u00bb na escola e \u00abaterrorizam\u00bb todos os que as rodeiam: sejam adultos ou crian\u00e7as. Os pais se cansam de combater sua teimosia e os professores n\u00e3o podem apenas esperar que esta crian\u00e7a problem\u00e1tica finalmente se forme ou saia da escola.<\/p>\n<p>Mas o que se esconde por tr\u00e1s de tal comportamento? Por que as crian\u00e7as se tornam \u00abproblem\u00e1ticas\u00bb? Quais erros os pais cometem ao criar seus filhos? E como fazer a crian\u00e7a realmente te escutar? Voc\u00ea encontrar\u00e1 respostas para essas perguntas neste artigo.<\/p>\n<p class=\"warning\">Para dar mais liberdade ao seu filho e parar de impor limites em suas atividades, ao mesmo tempo garantir sua seguran\u00e7a, fa\u00e7a o download do aplicativo \u00abFindmykids\u00bb na <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">AppStore<\/a> ou <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">GooglePlay<\/a>.<\/p>\n<h2>Conte\u00fados:<\/h2>\n<ul class=\"contents\">\n<li><a href=\"#O\">O retrato de uma crian\u00e7a problem\u00e1tica<\/a><\/li>\n<li><a href=\"#Por\">Por que as crian\u00e7as se tornam \u00abdif\u00edceis\u00bb e incontrol\u00e1veis?<\/a>\n<ul>\n<li><a href=\"#Erros\">Erros dos pais<\/a><\/li>\n<li><a href=\"#Poss\u00edveis\">Poss\u00edveis motivos para o mal comportamento de uma crian\u00e7a<\/a><\/li>\n<li><a href=\"#Crises\">Crises relacionada a faixas et\u00e1rias<\/a><\/li>\n<li><a href=\"#Motivos\">Motivos fisiol\u00f3gicos<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"#educada?\">O que fazer com uma crian\u00e7a mal-educada?<\/a>\n<ul>\n<li><a href=\"#castigos\">Vale a pena os castigos?<\/a><\/li>\n<li><a href=\"#problem\u00e1ticas\">Dicas de um psic\u00f3logo para pais de crian\u00e7as problem\u00e1ticas<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"O\">O retrato de uma crian\u00e7a problem\u00e1tica<\/h2>\n<div id=\"attachment_6294\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6294\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6294\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Detskaya-isterika.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6294\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Um pai leva um menino de seis anos a uma consulta com um psic\u00f3logo. A crian\u00e7a \u00e9 incapaz de controlar seu comportamento: est\u00e1 constantemente pulando, mexendo nos brinquedos do consult\u00f3rio sem permiss\u00e3o e batendo as portas. Quando entediada, a crian\u00e7a vai mexer nas cortinas e de tanto puxar, acaba quebrando. O pai ent\u00e3o explica que, na creche, os professores n\u00e3o conseguem lidar com o menino, que os ignora e continua fazendo o que bem entende: correndo, quebrando brinquedos, gritando alto durante o momento da soneca. O menino n\u00e3o consegue fazer amigos, pois as demais crian\u00e7as ficam longe dele, ningu\u00e9m quer brincar com ele ou fazer qualquer atividade juntos.<\/p>\n<p>Este \u00e9 um exemplo t\u00edpico de uma crian\u00e7a problem\u00e1tica. Tais crian\u00e7as:<\/p>\n<ul>\n<li>n\u00e3o controlam seu pr\u00f3prio comportamento;<\/li>\n<li>n\u00e3o levam em considera\u00e7\u00e3o os sentimentos e emo\u00e7\u00f5es de si pr\u00f3prios e nem dos demais;<\/li>\n<li>n\u00e3o seguem c\u00f3digos de conduta nas institui\u00e7\u00f5es pr\u00e9-escolar e escolar;<\/li>\n<li>n\u00e3o obedecem aos pais e professores;<\/li>\n<li>geralmente s\u00e3o bastante mal-humorados e fazem birras;<\/li>\n<li>n\u00e3o sabem se comportar adequadamente em locais p\u00fablicos;<\/li>\n<li>t\u00eam comportamentos que irritam os adultos;<\/li>\n<li>tornam-se p\u00e1rias entre as crian\u00e7as da mesma faixa et\u00e1ria.<\/li>\n<\/ul>\n<h2 id=\"Por\">Por que as crian\u00e7as se tornam \u00abdif\u00edceis\u00bb e incontrol\u00e1veis?<\/h2>\n<div id=\"attachment_6291\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6291\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6291\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Vopit.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6291\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<h3 id=\"Erros\">Erros dos pais<\/h3>\n<h4><strong>Erro \u21161. Criar um \u00abfilhinho de papai\u00bb<\/strong><\/h4>\n<p>Os pais atendem todas as necessidades e desejos de seu filho. Essa situa\u00e7\u00e3o geralmente ocorre quando a crian\u00e7a \u00e9 o \u00fanico filho da fam\u00edlia ou quando \u00e9 muito desejada. Como resultado, ela se acostuma com sua grande import\u00e2ncia e n\u00e3o considera nenhuma proibi\u00e7\u00e3o e restri\u00e7\u00e3o dos adultos.<\/p>\n<h4><strong>Erro \u21162. A aus\u00eancia de puni\u00e7\u00f5es e da forma\u00e7\u00e3o de um senso de responsabilidade por suas a\u00e7\u00f5es desde cedo<\/strong><\/h4>\n<p>A crian\u00e7a \u00e9 sempre perdoada por m\u00e1s a\u00e7\u00f5es e desobedi\u00eancias sob uma simples explica\u00e7\u00e3o: \u00abela ainda \u00e9 muito pequena e n\u00e3o sabe o que est\u00e1 fazendo. Quando crescer, vai compreender\u00bb.<\/p>\n<h4><strong>Erro \u21163. Um tratamento excessivamente cuidadoso<\/strong><\/h4>\n<div id=\"attachment_6147\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6147\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6147\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya-1232x821.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Malchik-spryatolsya.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6147\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>A constante abordagem do \u00ablaissez-faire\u00bb \u00e9 t\u00e3o perigosa quanto as proibi\u00e7\u00f5es e restri\u00e7\u00f5es recorrentes, pois elas criam o desejo de viol\u00e1-las. Em especial, quando as necessidades fundamentais da crian\u00e7a s\u00e3o limitadas: seja em sua atividade f\u00edsica, comunica\u00e7\u00e3o ou explora\u00e7\u00e3o do mundo ao seu redor.<\/p>\n<p class=\"warning\">Para dar mais liberdade ao seu filho e parar de impor limites em suas atividades, ao mesmo tempo garantir sua seguran\u00e7a, fa\u00e7a o download do aplicativo \u00abFindmykids\u00bb na <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">AppStore<\/a> ou <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">GooglePlay<\/a>.<\/p>\n<h4><strong>Erro \u21164<\/strong>. <strong>Padr\u00f5es comportamentais incorretos criados pelos pais<\/strong><\/h4>\n<p>Serm\u00f5es sobre os perigos de fumar e os benef\u00edcios da leitura podem ser feitos em casa diariamente, mas se os pais fumam e os livros n\u00e3o passam de enfeites nas estantes, \u00e9 pouco prov\u00e1vel que esta crian\u00e7a compreenda o que est\u00e1 sendo dito e mude seu comportamento.<\/p>\n<h4><strong>Erro \u21165. A falta de uma distin\u00e7\u00e3o clara entre o que \u00e9 permitido e o que n\u00e3o \u00e9<\/strong><\/h4>\n<p>Se a m\u00e3e terminantemente pro\u00edbe que a crian\u00e7a coma doces, mas a av\u00f3 oferece escondido, ou o pai chega em casa do trabalho de bom humor e permite que ela fique acordada at\u00e9 depois de meia-noite, a crian\u00e7a ir\u00e1 se adaptar rapidamente \u00e0 natureza mut\u00e1vel do humor nos adultos e aprender\u00e1 como manipul\u00e1-los para conseguir o que deseja.<\/p>\n<h4><strong>Erro \u21166. \u00abTerceirizar\u00bb a educa\u00e7\u00e3o<\/strong><\/h4>\n<p>A opini\u00e3o dos pais, neste caso, \u00e9 de que a creche e a escola \u00e9 que devem educar seus filhos. A justificativa \u00e9 de que n\u00e3o t\u00eam tempo para isso, pois est\u00e3o ocupados ganhando dinheiro para sustentar a fam\u00edlia.<\/p>\n<p><div class=\"post_header_video\"><iframe src=\"https:\/\/www.youtube.com\/embed\/gRSOa50XdMI\" frameborder=\"0\" allowfullscreen> width=\"704\" height=\"396\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div><\/p>\n<h3 id=\"Poss\u00edveis\">Poss\u00edveis motivos para o mal comportamento de uma crian\u00e7a<\/h3>\n<p>Al\u00e9m dos erros que os pais cometem ao criar um filho, existem ainda outras raz\u00f5es pelas quais uma crian\u00e7a tranquila e obediente pode come\u00e7ar a se comportar mal de repente:<\/p>\n<h4><strong>1. Desejo de chamar a aten\u00e7\u00e3o<\/strong><\/h4>\n<p>Quando mam\u00e3e e papai est\u00e3o sempre trabalhando, os filhos veem seus pais apenas de manh\u00e3 e de noite. Portanto, muitas vezes, eles n\u00e3o recebem o amor e carinho que desejam e necessitam. Nos fins de semana, muitos pais deixam os filhos com os av\u00f3s ao lidar com as tarefas dom\u00e9sticas acumuladas.<\/p>\n<p class=\"warning\">Naturalmente, esta crian\u00e7a busca a aten\u00e7\u00e3o dos pais de qualquer forma. E, como voc\u00ea j\u00e1 sabe, a maneira mais r\u00e1pida e f\u00e1cil de fazer com que a m\u00e3e ou o pai prestem aten\u00e7\u00e3o imediatamente: fa\u00e7a uma cena, comece a gritar e bater os p\u00e9s na rua ou entre em uma briga com um colega.<\/p>\n<p>O que os pais devem fazer:<\/p>\n<ul>\n<li>chame a crian\u00e7a pelo nome com mais frequ\u00eancia e diga-lhe palavras gentis com frequ\u00eancia;<\/li>\n<li>se o mau comportamento da crian\u00e7a \u00e9 causado pela falta de aten\u00e7\u00e3o dos pais, \u00e9 melhor n\u00e3o reagir a esse comportamento do seu filho para n\u00e3o estimular.<\/li>\n<li>se a crian\u00e7a come\u00e7ar a se comportar mal, distra\u00ed-a. D\u00ea a ela uma tarefa f\u00e1cil, como regar as plantas, arrumar seus brinquedos ou lavar a lou\u00e7a. Sempre demonstre sua gratid\u00e3o quando a crian\u00e7a concluir tais tarefas;<\/li>\n<li>passe seu tempo livre com seu filho: fa\u00e7a passeios e brinquem juntos. Demonstre que a crian\u00e7a \u00e9 uma parte importante da sua vida e n\u00e3o um inc\u00f4modo.<\/li>\n<\/ul>\n<h4><strong>2. A \u00absede de poder\u00bb<\/strong><\/h4>\n<div id=\"attachment_6146\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6146\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6146\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Devochka-s-otkrytom-rtom-1232x821.jpg 1232w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-6146\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Muitas crian\u00e7as, especialmente em tempos de crise, exigem que todos os seus desejos e necessidades sejam satisfeitos. A crian\u00e7a tenta dominar seus pais, tornando-se mais independente deles.<\/p>\n<p>Isto pode se expressar atrav\u00e9s do mau humor, desobedi\u00eancia, recusa em ouvir os adultos, insist\u00eancia em sua pr\u00f3pria opini\u00e3o.<\/p>\n<p>O que os pais devem fazer:<\/p>\n<ul>\n<li>reconhecer o poder e a import\u00e2ncia da crian\u00e7a. No entanto, esse poder deve ser acompanhado de responsabilidades. Por exemplo, a m\u00e3e permite que a filha use seu vestido de festa favorito em um dia da semana na creche, mas se ela se sujar, ter\u00e1 que usar um vestido diferente para uma festa.<\/li>\n<li>definir limites claros para o que \u00e9 um comportamento inaceit\u00e1vel. Deve estar claro que n\u00e3o \u00e9 permitido brigar e xingar os pais, outros adultos ou crian\u00e7as; da mesma maneira, n\u00e3o \u00e9 permitido quebrar seus brinquedos ou os dos colegas. Caso a crian\u00e7a ultrapassar esses limites, ela deve ser repreendida. Tudo isso deve ser conversado previamente com a crian\u00e7a, para que ela saiba quais s\u00e3o as consequ\u00eancias de suas atitudes incorretas.<\/li>\n<li>ensinar a seu filho como controlar seus atos e suas emo\u00e7\u00f5es e tamb\u00e9m a lidar com a raiva e a agress\u00e3o.<\/li>\n<\/ul>\n<h4><strong>3. Vingan\u00e7a (\u00abVoc\u00ea fez algo ruim para mim, eu vou fazer o mesmo com voc\u00ea\u00bb)<\/strong><\/h4>\n<p>N\u00f3s mesmos \u00e0s vezes n\u00e3o percebemos que nossas a\u00e7\u00f5es ou palavras podem ofender nossos filhos. Ainda que, para n\u00f3s, isso possa passar despercebido e um conflito possa acabar sendo considerado pouco importante, o ressentimento pode ter s\u00e9rias consequ\u00eancias para uma crian\u00e7a.<\/p>\n<p>Em primeiro lugar, ela pode se tornar antissocial e passar a ter demonstra\u00e7\u00f5es de agress\u00e3o f\u00edsica ou verbal contra o adulto, se comporta mal e n\u00e3o obedecer os pais de forma alguma. Como consequ\u00eancia, pode surgir a constru\u00e7\u00e3o de um relacionamento mais forte entre a crian\u00e7a e seus pais ou, pelo contr\u00e1rio, um distanciamento ainda maior entre eles.<\/p>\n<div id=\"attachment_5911\" style=\"width: 760px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5911\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-5911\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/agresivnost-1232x821.jpg 1232w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-5911\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>O que os pais devem fazer:<\/p>\n<ul>\n<li>ensinar seus filhos a expressar seus sentimentos e preocupa\u00e7\u00f5es. Pergunte com mais frequ\u00eancia: \u00abO que voc\u00ea est\u00e1 sentindo? Como est\u00e1 seu humor hoje?\u00bb;<\/li>\n<li>ap\u00f3s brigar com a crian\u00e7a: pe\u00e7a desculpas, se voc\u00ea n\u00e3o conseguiu manter a calma e gritou com eles, converse sobre o que causou a briga e o que pode ser feito para que isso n\u00e3o aconte\u00e7a mais no futuro;<\/li>\n<li>n\u00e3o tenha medo de expressar seus sentimentos na frente de seu filho. Sua autoridade n\u00e3o sofrer\u00e1 abalos com isso. Sim, \u00e0s vezes voc\u00ea pode se sentir triste e envergonhado por seus erros.<\/li>\n<\/ul>\n<h4><strong>4. Conscientemente evitando falhar<\/strong><\/h4>\n<p>Essa crian\u00e7a se recusa a participar de jogos, competi\u00e7\u00f5es esportivas e eventos, n\u00e3o responde \u00e0s perguntas do professor na frente da turma, tem medo de visitar novos lugares e de conhecer novas pessoas.<\/p>\n<p>Adultos acreditam que essa \u00e9 apenas uma forma de agir por meio da desobedi\u00eancia, por\u00e9m o problema aqui \u00e9 muito mais profundo. Trata-se da percep\u00e7\u00e3o individual e da autoestima da crian\u00e7a.<\/p>\n<p class=\"warning\">A crian\u00e7a tem medo de falhar, de ter \u00eaxito e, portanto, recusa situa\u00e7\u00f5es que podem ser potencialmente traum\u00e1ticas. Os pais tamb\u00e9m contribuem para isso, quando suas expectativas em rela\u00e7\u00e3o \u00e0 crian\u00e7a n\u00e3o correspondem \u00e0s suas reais capacidades.<\/p>\n<p>O que os pais devem fazer:<\/p>\n<ul>\n<li>criar situa\u00e7\u00f5es de &#8216;ganha-ganha&#8217; nas quais a crian\u00e7a \u00e9 capaz de demonstrar seus pontos fortes;<\/li>\n<li>aumentar a autoestima da crian\u00e7a, elogi\u00e1-la por sua perseveran\u00e7a e por concluir suas tarefas;<\/li>\n<li>ensinar a pensar de uma forma positiva sobre si mesmo: \u00abSim, ainda n\u00e3o sei amarrar meus cadar\u00e7o, mas n\u00e3o tem problema, j\u00e1 consigo construir uma casa de Lego em cinco minutos\u00bb;<\/li>\n<li>n\u00e3o comparar seu filho com as outras crian\u00e7as. Compare-o apenas consigo mesmo, com suas a\u00e7\u00f5es e realiza\u00e7\u00f5es pessoais;<\/li>\n<li>apoiar e sempre ajudar em caso de dificuldades, mas n\u00e3o fa\u00e7a suas tarefas por eles!<\/li>\n<\/ul>\n<h3 id=\"Crises\">Crises relacionada a faixas et\u00e1rias<\/h3>\n<div id=\"attachment_5907\" style=\"width: 759px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5907\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-5907\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-1024x683.jpg\" alt=\"\" width=\"749\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-768x513.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-392x262.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/rebenok-plachet-1232x822.jpg 1232w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><p id=\"caption-attachment-5907\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p><strong>Aos 3 anos<\/strong><\/p>\n<p>Aos tr\u00eas anos de idade, a crian\u00e7a come\u00e7a a lutar para conquistar sua independ\u00eancia do adulto. Geralmente s\u00e3o teimosos, recusam-se a cumprir os pedidos dos pais e fazem birras com frequ\u00eancia. Muitas vezes, m\u00e3es e pais n\u00e3o est\u00e3o preparados para o fato de que seu beb\u00ea fofo se transforma subitamente em um tirano incontrol\u00e1vel. Mas essas manifesta\u00e7\u00f5es n\u00e3o devem ser temidas, pois sugerem apenas que a crian\u00e7a est\u00e1 crescendo e que est\u00e1 pronta para se separar psicologicamente do adulto e come\u00e7ar a se tornar um indiv\u00edduo independente, com suas pr\u00f3prias necessidades e desejos.<\/p>\n<p><strong>Aos 6\/7 anos<\/strong><\/p>\n<p>O pr\u00f3ximo momento de crise da vida da crian\u00e7a \u00e9 na idade pr\u00e9-escolar, quando o seu \u00abeu\u00bb social come\u00e7a a tomar forma. Da mesma forma que aos 3 anos de idade, a crian\u00e7a quer tomar suas pr\u00f3prias decis\u00f5es e quer que os adultos levem em considera\u00e7\u00e3o sua opini\u00e3o. As crian\u00e7as podem demonstrar uma rea\u00e7\u00e3o ruim \u00e0s cr\u00edticas, muitas vezes ficam ofendidas e desobedecem quando os pais exigem que suas regras sejam cumpridas sem perguntas.<\/p>\n<p><strong>Durante a adolesc\u00eancia<\/strong><\/p>\n<p>Um adolescente est\u00e1 buscando formas de se expressar e se autoafirmar perante a sociedade, enquanto a opini\u00e3o dos pais deixa de ser autorit\u00e1ria para eles. Altera\u00e7\u00f5es hormonais causam explosividade, irritabilidade e instabilidade emocional. Muitas crian\u00e7as come\u00e7am a apresentar um desempenho acad\u00eamico mais fraco e surgem os conflitos com colegas e professores. Uma atmosfera hostil tamb\u00e9m reina na fam\u00edlia neste momento, pois os pais podem tentar assumir o controle da vida de seu filho.<\/p>\n<p class=\"warning\">Se voc\u00ea est\u00e1 preocupado com seu filho adolescente, se suspeita que ele esteja envolvido com um grupo de amigos \u00abruins\u00bb, que est\u00e1 sofrendo bullying dos colegas ou apenas se quer ter certeza de que tudo est\u00e1 bem na escola, n\u00e3o \u00e9 necess\u00e1rio coloc\u00e1-lo sob um controle r\u00edgido. Basta baixar o aplicativo \u00abFindmykids\u00bb na <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">AppStore<\/a> ou  <a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras1\">GooglePlay<\/a>.<\/p>\n<h3 id=\"Motivos\">Motivos fisiol\u00f3gicos<\/h3>\n<div id=\"attachment_5903\" style=\"width: 677px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5903\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-5903\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-1024x768.jpg\" alt=\"\" width=\"667\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-1024x768.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-150x113.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-300x225.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-768x576.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-600x450.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-200x150.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-808x606.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-392x294.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak-1232x924.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/10\/kylak.jpg 1920w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><p id=\"caption-attachment-5903\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Al\u00e9m dos motivos mencionados acima, os dist\u00farbios comportamentais podem se manifestar em crian\u00e7as associado aos seguintes problemas fisiol\u00f3gicos:<\/p>\n<ul>\n<li>TDAH (transtorno do d\u00e9ficit de aten\u00e7\u00e3o e hiperatividade);<\/li>\n<li>TEA (transtorno do espectro autista);<\/li>\n<li>Atraso no desenvolvimento;<\/li>\n<li>Doen\u00e7a mental;<\/li>\n<li>Trauma psicol\u00f3gico ou estresse constante<\/li>\n<\/ul>\n<p>Nesses casos, a atua\u00e7\u00e3o dos pais apenas n\u00e3o ser\u00e1 suficiente. A crian\u00e7a precisa de assist\u00eancia m\u00e9dica, psicol\u00f3gica e educacional.<\/p>\n<p>Lembra do garoto que foi ao psic\u00f3logo com o pai? No caso dele, havia uma gama de raz\u00f5es que agiam como motivadoras para tal comportamento. Os pais se separaram quando n\u00e3o tinha nem tr\u00eas anos e sua av\u00f3 participava ativamente de sua educa\u00e7\u00e3o, pois os pais tinham suas prioridades definidas em sua vida pessoal. Depois que a av\u00f3 percebeu rapidamente que n\u00e3o era capaz de lidar com o menino, ela tentou envolver os pais no processo de cria\u00e7\u00e3o. Assim, o menino passou a morar com o pai e a nova esposa, ficando algumas vezes com a av\u00f3 e, ocasionalmente, a m\u00e3e o buscava nos fins de semana. Com est\u00e1 situa\u00e7\u00e3o familiar, a crian\u00e7a n\u00e3o se sentia amada nem valorizada. Essa neglig\u00eancia veio sob a forma de seus dist\u00farbios neurol\u00f3gicos, aos quais os pais n\u00e3o prestaram aten\u00e7\u00e3o.<\/p>\n<h2 id=\"educada?\">O que fazer com uma crian\u00e7a mal-educada?<\/h2>\n<div id=\"attachment_6140\" style=\"width: 759px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6140\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6140\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-1024x683.jpg\" alt=\"\" width=\"749\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-1024x683.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-300x200.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-768x512.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-808x539.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-392x262.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel-1232x822.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Strogiy-roditel.jpg 1920w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><p id=\"caption-attachment-6140\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<h3 id=\"castigos\">Vale a pena os castigos?<\/h3>\n<p>O tema castigo sempre causa muita controv\u00e9rsia entre os pais. Alguns acreditam que o castigo abala a identidade da crian\u00e7a e a priva de sua independ\u00eancia. Outros relembram a pr\u00f3pria inf\u00e2ncia \u00abFiquei de castigo in\u00fameras vezes at\u00e9 os 10 anos de idade, meu pai at\u00e9 me batia em algumas ocasi\u00f5es\u00bb e acaba agindo da mesma maneira com os filhos. Alguns usam o castigo apenas como uma amea\u00e7a (\u00abse voc\u00ea n\u00e3o parar de brincar agora, vai ficar de castigo\u00bb), mas, na realidade, isso n\u00e3o ocorre.<\/p>\n<p>J\u00e1 se descobriu que a total falta de puni\u00e7\u00e3o e responsabilidade pelas a\u00e7\u00f5es leva ao desenvolvimento de uma sensa\u00e7\u00e3o de que tudo \u00e9 permitido e contribui para uma falta de vontade de obedecer aos pedidos dos adultos.<\/p>\n<p>Portanto, os pais devem definir as regras para os castigos e obedec\u00ea-las sempre:<\/p>\n<ol>\n<li>O objetivo do castigo \u00e9 conscientizar a crian\u00e7a de seu \u00aberro\u00bb e, a partir de ent\u00e3o, motiv\u00e1-la a agir de maneira diferente. N\u00e3o haver\u00e1 um dano f\u00edsico ou psicol\u00f3gico por essa puni\u00e7\u00e3o.<\/li>\n<li>A crian\u00e7a deve ter certeza de que, embora fique de castigo, seus pais continuar\u00e3o a am\u00e1-la.<\/li>\n<li>O castigo deve ser relacionado a um ato espec\u00edfico que a crian\u00e7a cometeu.<\/li>\n<li>Nunca castigue uma crian\u00e7a com raiva e, principalmente, em locais p\u00fablicos.<\/li>\n<li>Leve em considera\u00e7\u00e3o a idade da crian\u00e7a. Castigar uma crian\u00e7a de dois anos por derrubar uma tigela de sopa sem querer n\u00e3o \u00e9 correto.<\/li>\n<li>O castigo n\u00e3o deve humilhar a crian\u00e7a.<\/li>\n<li>Se voc\u00ea foi informado sobre o mau comportamento da crian\u00e7a, escute-a primeiro e depois tome uma decis\u00e3o sobre a puni\u00e7\u00e3o.<\/li>\n<li>O castigo onde existe alguma priva\u00e7\u00e3o n\u00e3o deve envolver o que j\u00e1 foi dado \u00e0 crian\u00e7a (seus doces ou brinquedos).<\/li>\n<li>Se poss\u00edvel, defina alguns comportamentos que s\u00e3o pass\u00edveis de castigo: quais ser\u00e3o essas a\u00e7\u00f5es e do que exatamente a crian\u00e7a ser\u00e1 privada.<\/li>\n<\/ol>\n<div id=\"attachment_6148\" style=\"width: 714px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-6148\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6148\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-1024x727.jpg\" alt=\"\" width=\"704\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-1024x727.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-150x106.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-300x213.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-768x545.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-600x426.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-200x142.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-808x574.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-392x278.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch-1232x875.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2019\/11\/Mama-celuet-doch.jpg 1920w\" sizes=\"(max-width: 704px) 100vw, 704px\" \/><p id=\"caption-attachment-6148\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p>Os seguintes castigos podem ser considerados psicologicamente \u00abseguros\u00bb:<\/p>\n<ol>\n<li>Intervalo (um tempo em que a crian\u00e7a deve passar sozinha).<\/li>\n<li>Uma proibi\u00e7\u00e3o tempor\u00e1ria de usar computadores, outros equipamentos eletr\u00f4nicos ou ver TV.<\/li>\n<li>Uma proibi\u00e7\u00e3o tempor\u00e1ria de comprar brinquedos ou doces.<\/li>\n<li>Uma conversa com a crian\u00e7a em um tom calmo.<\/li>\n<li>Uma busca coletiva para solu\u00e7\u00f5es construtivas.<\/li>\n<li>A corre\u00e7\u00e3o dos pr\u00f3prios erros pela crian\u00e7a, quando poss\u00edvel.<\/li>\n<\/ol>\n<p>Em 2017, foi realizada uma pesquisa sobre o castigo em crian\u00e7as (pelos pais). Nele, um MCQ foi proposto. Os resultados foram os seguintes:<\/p>\n<ul>\n<li>80% dos pais usam alguma conversa com uma moral oculta;<\/li>\n<li>12% aplicam castigos f\u00edsicos usando cintos;<\/li>\n<li>43% restringem o acesso ao computador por algum tempo;<\/li>\n<li>29% deixam a crian\u00e7a sozinha para refletir sobre seus atos;<\/li>\n<li>13% suspendem a mesada das crian\u00e7as.<\/li>\n<\/ul>\n<h3 id=\"problem\u00e1ticas\">Dicas de um psic\u00f3logo para pais de crian\u00e7as problem\u00e1ticas<\/h3>\n<div id=\"attachment_4479\" style=\"width: 677px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-4479\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-4479 size-full\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/08\/communication-with-child.jpg\" alt=\"\" width=\"667\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2019\/08\/communication-with-child.jpg 667w, https:\/\/cdn-blog.findmykids.org\/2019\/08\/communication-with-child-150x112.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2019\/08\/communication-with-child-300x225.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2019\/08\/communication-with-child-392x294.jpg 392w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><p id=\"caption-attachment-4479\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<ul>\n<li>Comece a criar seu filho dando um exemplo. Seguir o seu exemplo de comportamento calmo e tranquilo trar\u00e1 muito mais resultados do que uma longa conversa cheia de moral.<\/li>\n<li>Ame seu filho de qualquer maneira: mal-humorado, travesso ou teimoso. 90% dos casos de desobedi\u00eancia em crian\u00e7as est\u00e3o associados \u00e0 falta de amor e aten\u00e7\u00e3o dos pais.<\/li>\n<li>\u00c9 importante que os pais tenham uma id\u00e9ia das fases \u00abcr\u00edticas\u00bb no desenvolvimento da crian\u00e7a. Dessa forma, ser\u00e1 mais f\u00e1cil para eles entender e reagir de acordo com determinado comportamento de seu filho.<\/li>\n<li>Ensine a crian\u00e7a a entender a si mesma, a analisar e refletir sobre seus sentimentos. Dessa forma, eles aprender\u00e3o a lidar melhor com esses sentimentos.<\/li>\n<li>N\u00e3o busque o t\u00edtulo de pai \u00abperfeito\u00bb com um filho \u00abperfeito\u00bb. Todos t\u00eam o direito de cometer erros.<\/li>\n<li>Preste aten\u00e7\u00e3o aos jogos que a crian\u00e7a brinca e aos desenhos que assiste. Quem s\u00e3o os her\u00f3is e pessoas que t\u00eam como modelos. Por exemplo, observe que o desenho animado \u00abTom e Jerry\u00bb descreve a rivalidade cl\u00e1ssica de gato e rato de uma maneira muito violenta e inclui cen\u00e1rios que podem ser reproduzidos em situa\u00e7\u00f5es da vida real em que envolvem itens dom\u00e9sticos. Muitos pais j\u00e1 se queixaram de seus filhos ficarem inquietos e mais propensos a a\u00e7\u00f5es violentas depois de assistirem.<\/li>\n<li>Os castigos devem ocorrer, mas n\u00e3o se esque\u00e7a das a\u00e7\u00f5es de incentivo e valoriza\u00e7\u00e3o do bom comportamento.<\/li>\n<li>Lembre-se: o bom comportamento pode ser alcan\u00e7ado n\u00e3o apenas atrav\u00e9s da puni\u00e7\u00e3o, mas tamb\u00e9m atrav\u00e9s de conversas.<\/li>\n<li>Se algo n\u00e3o \u00e9 permitido \u00e0 crian\u00e7a, n\u00e3o deve ser permitido sob nenhuma circunst\u00e2ncia, independente do humor dos pais.<div id=\"attachment_8076\" style=\"width: 762px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-8076\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-8076\" src=\"https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-1024x681.jpg\" alt=\"\" width=\"752\" height=\"500\" srcset=\"https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-1024x681.jpg 1024w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-150x100.jpg 150w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-300x199.jpg 300w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-768x510.jpg 768w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-600x400.jpg 600w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-200x133.jpg 200w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-808x537.jpg 808w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-392x261.jpg 392w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain-1232x819.jpg 1232w, https:\/\/cdn-blog.findmykids.org\/2020\/02\/girl-pain.jpg 1920w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><p id=\"caption-attachment-8076\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div><\/li>\n<li>Aprenda a reagir \u00e0s birras do seu filho. A crian\u00e7a de tr\u00eas anos pode se distrair com algo interessante na rua ou em casa, \u00e9 melhor ignorar a birra da crian\u00e7a mais velha e, depois que a crian\u00e7a se acalma, conversar sobre o que est\u00e1 errado.<\/li>\n<li>Se voc\u00ea n\u00e3o consegue lidar com o problema do mau comportamento de uma crian\u00e7a, procure um psic\u00f3logo para obter ajuda.<\/li>\n<li>Medicamentos s\u00f3 devem ser usados conforme indicado pelo seu m\u00e9dico!<\/li>\n<li>Se voc\u00ea amea\u00e7ou punir a crian\u00e7a, castigue, se voc\u00ea prometeu encoraj\u00e1-la, fa\u00e7a. Mantenha suas promessas. E a crian\u00e7a aprender\u00e1 a fazer o mesmo.<\/li>\n<li>Tocar, abra\u00e7ar, beijar ou segurar a m\u00e3o da crian\u00e7a \u00e9 a melhor maneira de lidar com o in\u00edcio de uma birra. Se a crian\u00e7a come\u00e7ar com uma birra em uma loja, no parquinho ou na rua, abaixe para ficar na mesma altura dela e explique com calma o erro de suas a\u00e7\u00f5es.<\/li>\n<li>N\u00e3o rotule seu filho. Se uma crian\u00e7a \u00e9 constantemente informada de que \u00e9 m\u00e1 e malcriada, mais cedo ou mais tarde ela realmente ir\u00e1 se tornar e se comportar de acordo.<\/li>\n<li>E a \u00faltima recomenda\u00e7\u00e3o: todas as regras de conduta, todos os \u00abFAZER\u00bb e \u00abN\u00c3O FAZER\u00bb ensinam a crian\u00e7a desde a inf\u00e2ncia, formam sua cultura de comportamento em casa e em locais p\u00fablicos.<\/li>\n<\/ul>\n<p>Queridos pais, lembre-se de que mesmo as crian\u00e7as mais \u00abdif\u00edceis\u00bb e incontrol\u00e1veis podem se tornar obedientes caso se sentam importantes, necess\u00e1rias e amadas. \u00c9 o seu amor e apoio que pode ajudar na luta contra o mau comportamento do seu filho!<\/p>\n<div id=\"attachment_3506\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3506\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3506\" src=\"https:\/\/cdn-blog.findmykids.org\/2019\/05\/brazilian-banner-fmk.jpg\" alt=\"brazilian banner fmk\" width=\"620\" height=\"305\" \/><p id=\"caption-attachment-3506\" class=\"wp-caption-text\">Prostock-studio\/Shutterstock.com<\/p><\/div>\n<p><a href=\"https:\/\/findmykids.onelink.me\/xY6s?pid=content_team&#038;c=pt&#038;af_channel=blog&#038;af_adset=article-br&#038;af_ad=criancas-problematicas-o-que-esta-escondido-por-tras-de-sua-desobediencia-e-birras\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-1578 size-full\" src=\"https:\/\/cdn-blog.findmykids.org\/2018\/09\/AppStore_GooglePlay_small.png\" alt=\"\" width=\"400\" height=\"84\" \/><\/a><\/p>\n\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"9516\"\n\t\t\t\t\tdata-ulike-nonce=\"3fdc26b0b4\"\n\t\t\t\t\tdata-ulike-type=\"likeThis\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-disable-pophover=\"0\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_likethis_9516\"><\/button><span class=\"count-box\">1<\/span>\t\t\t<\/div><\/div>\n\t","protected":false},"excerpt":{"rendered":"<p>\u00abInquieta, travessa, mal educada, em suma, uma crian\u00e7a problem\u00e1tica\u00bb. Ouvimos essas palavras com muita frequ\u00eancia&#8230;<\/p>\n","protected":false},"author":4,"featured_media":8760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"classic-editor-remember":["classic-editor"],"_edit_lock":["1624272185:4"],"_edit_last":["4"],"mpulseenable_meta_value":["no"],"ytrssenabled_meta_value":["no"],"ytremove_meta_value":["no"],"ytad1meta":["enabled"],"ytad2meta":["enabled"],"ytad3meta":["enabled"],"ytad4meta":["enabled"],"ytad5meta":["enabled"],"template_meta":["no"],"yzcategory_meta_value":["\u0414\u043e\u043c"],"yzrating_meta_value":["\u041d\u0435\u0442 (\u043d\u0435 \u0434\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445)"],"yzrssenabled_meta_value":["no"],"_s2mail":["yes"],"amphtml_featured_image_id":["0"],"amphtml-exclude":["0"],"amphtml-override-title":[""],"amphtml-override-content":[""],"\u0430\u0432\u0442\u043e\u0440":["Tatiana Freire"],"_\u0430\u0432\u0442\u043e\u0440":["field_5e33cab3984d1"],"\u0444\u043e\u0442\u043e":[""],"_\u0444\u043e\u0442\u043e":["field_5e33cbc1984d2"],"hide-in-popular":[""],"_hide-in-popular":["field_5d0c8a5b4fde2"],"_thumbnail_id":["8760"],"lang-en":["9299"],"lang-ru":["8703"],"layf_related_links":[""],"layf_exclude_from_feed":["0"],"ampforwp_custom_content_editor":[""],"ampforwp_custom_content_editor_checkbox":[null],"ampforwp-amp-on-off":["default"],"_aioseop_description":["O que significa uma crian\u00e7a dif\u00edcil e rebelde? O que est\u00e1 por tr\u00e1s deste comportamento? Como fazer uma crian\u00e7a obedecer? Voc\u00ea encontrar\u00e1 respostas para essas perguntas neste artigo."],"_aioseop_title":["Crian\u00e7as dif\u00edceis e malcriadas: o que os pais devem fazer, como cri\u00e1-los corretamente "],"_fmk_faq_pairs":["a:0:{}"],"_fmk_faq_hash":["16fd6f46f30de0c361948990b6c23ce2"]},"categories":[94],"tags":[],"language":[62],"acf":{"custom_title":"","custom_image":null,"custom_alt":"","read_more":null,"article_audio":null},"aioseo_notices":[],"featured_image_src":"https:\/\/cdn-blog.findmykids.org\/2020\/03\/boy-676122_1920.jpg","author_info":{"display_name":"Find My Kids","author_link":"https:\/\/findmykids.org\/blog\/ru\/author\/karpova"},"jetpack_featured_media_url":"https:\/\/cdn-blog.findmykids.org\/2020\/03\/boy-676122_1920.jpg","reading_time":"12","_links":{"self":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/9516"}],"collection":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/comments?post=9516"}],"version-history":[{"count":11,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/9516\/revisions"}],"predecessor-version":[{"id":19866,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/posts\/9516\/revisions\/19866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media\/8760"}],"wp:attachment":[{"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/media?parent=9516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/categories?post=9516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/tags?post=9516"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/findmykids.org\/blog\/wp-json\/wp\/v2\/language?post=9516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}